{"id":1309,"date":"2025-06-16T13:06:23","date_gmt":"2025-06-16T13:06:23","guid":{"rendered":"https:\/\/competent-ardinghelli.37-148-207-16.plesk.page\/?page_id=1309"},"modified":"2026-05-07T09:36:36","modified_gmt":"2026-05-07T09:36:36","slug":"studium","status":"publish","type":"page","link":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/","title":{"rendered":"Studium"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1309\" class=\"elementor elementor-1309\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0095ac e-flex e-con-boxed e-con e-parent\" data-id=\"f0095ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16eefaa e-con-full e-flex e-con e-child\" data-id=\"16eefaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa12563 elementor-widget elementor-widget-breadcrumbs\" data-id=\"fa12563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/karriere.hameln-pyrmont.de\/\">Startseite<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95805ef elementor-widget elementor-widget-heading\" data-id=\"95805ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Studium<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f9abc2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7f9abc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dein Karrierestart mit Perspektive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87bb9de e-flex e-con-boxed e-con e-parent\" data-id=\"87bb9de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16c729d e-con-full e-flex e-con e-child\" data-id=\"16c729d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b031536 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b031536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 32H336c-26.5 0-48 21.5-48 48v128c0 26.5 21.5 48 48 48h80v64c0 35.3-28.7 64-64 64h-8c-13.3 0-24 10.7-24 24v48c0 13.3 10.7 24 24 24h8c88.4 0 160-71.6 160-160V80c0-26.5-21.5-48-48-48zm-288 0H48C21.5 32 0 53.5 0 80v128c0 26.5 21.5 48 48 48h80v64c0 35.3-28.7 64-64 64h-8c-13.3 0-24 10.7-24 24v48c0 13.3 10.7 24 24 24h8c88.4 0 160-71.6 160-160V80c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8be8b94 elementor-widget elementor-widget-heading\" data-id=\"8be8b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Hier bin ich HaPy,<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e214c4c elementor-widget elementor-widget-text-editor\" data-id=\"e214c4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>weil der Landkreis die Weiterbildung seiner Mitarbeitenden stetig f\u00f6rdert. Ich habe dadurch direkt im Anschluss meiner Ausbildung die M\u00f6glichkeit auf einen Studienplatz erhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-779636a elementor-widget elementor-widget-text-editor\" data-id=\"779636a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Verena Borchers<br \/><\/strong>Duale Studentin der Verwaltungswissenschaften<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f74685c e-con-full e-flex e-con e-child\" data-id=\"f74685c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04eaae9 elementor-widget elementor-widget-image\" data-id=\"04eaae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg\" title=\"0V0A5234\" alt=\"0V0A5234\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-451d0d6 e-con-full e-flex e-con e-parent\" data-id=\"451d0d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2576769 e-con-full e-flex e-con e-child\" data-id=\"2576769\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed9c3d elementor-widget elementor-widget-counter\" data-id=\"8ed9c3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Auszubildende &amp; Studierende<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"40\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62f6b19 e-con-full e-flex e-con e-child\" data-id=\"62f6b19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-56075b7 e-flex e-con-boxed e-con e-child\" data-id=\"56075b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bca6771 elementor-widget elementor-widget-heading\" data-id=\"bca6771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dein Einstieg beim Landkreis Hameln-Pyrmont<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e84c98 elementor-widget elementor-widget-text-editor\" data-id=\"2e84c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit einem Studium in der \u00f6ffentlichen Verwaltung liegst du richtig, wenn du auf Entwicklungschancen setzt und gleichzeitig Wert auf Sicherheit legst. W\u00e4hrend des Studiums sammelst du bereits praktische Erfahrungen in verschiedenen Verwaltungsbereichen wie Personal, Finanzen oder Organisation. Nach dem Studium stehen dir zahlreiche T\u00e4tigkeitsfelder offen \u2013 von der Sachbearbeitung \u00fcber Projektmanagement bis hin zu Leitungsfunktionen. Du kannst dich auf unterschiedliche Fachgebiete spezialisieren und aktiv an der Weiterentwicklung von Verwaltungsprozessen mitwirken.<\/p><p>Wir bieten folgende duale Studieng\u00e4nge an:\u00a0<\/p><ul><li><span style=\"background-color: transparent;\">Duales Studium der Verwaltungswissenschaften<\/span><\/li><\/ul><ul><li>Duales Studium der Sozialen Arbeit<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a55561d e-flex e-con-boxed e-con e-parent\" data-id=\"a55561d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d621c2 e-con-full e-flex e-con e-child\" data-id=\"7d621c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-041f2d0 elementor-widget elementor-widget-n-accordion\" data-id=\"041f2d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4320\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-4320\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h2 class=\"e-n-accordion-item-title-text\"> Mehr Infos zum Dualen Studium der Verwaltungswissenschaften <\/h2><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4320\" class=\"elementor-element elementor-element-ce90686 e-flex e-con-boxed e-con e-child\" data-id=\"ce90686\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4320\" class=\"elementor-element elementor-element-9a4ebf6 e-con-full e-flex e-con e-child\" data-id=\"9a4ebf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dafc2e8 elementor-widget elementor-widget-text-editor\" data-id=\"dafc2e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das duale Studium der Verwaltungswissenschaften dauert drei Jahre, die sich in 24 Monate Theorie- und 12 Monate Praxiszeit aufteilen. Es endet mit dem Abschluss Bachelor of Arts (B. A.) und bietet die M\u00f6glichkeit zur Spezialisierung auf Betriebswirtschaft oder Recht.<\/p><p>Du bist in der Zeit Kreisinspektoren-Anw\u00e4rter:in im Beamtenverh\u00e4ltnis\u00a0und studierst am Nieders\u00e4chsischen Studieninstitut in Hannover rechts-, wirtschafts- und sozialwissenschaftliche Inhalte. In der berufspraktischen Zeit durchl\u00e4ufst du verschiedene Organisationseinheiten unseres Landkreises.<\/p><p>Au\u00dferdem stehen zwei Monate Fremdausbildung bei einer anderen Verwaltung in Deutschland oder im Ausland auf dem Programm.<\/p><p>Selbstverst\u00e4ndlich \u00fcbernehmen wir die Studiengeb\u00fchren und du erh\u00e4ltst eine Verg\u00fctung in H\u00f6he von 1.469,74 Euro.<\/p><p>F\u00fcr ein erfolgreiches Studium musst du Folgendes mitbringen:<\/p><ul class=\" ikiss-unordered-list\"><li>mindestes Fachhochschulreife<\/li><li>Interesse an Verwaltungst\u00e4tigkeiten<\/li><li>logisches Denken und kommunikative St\u00e4rke<\/li><li>Sensibilit\u00e4t und Taktgef\u00fchl im Umgang mit Menschen<\/li><li>Entscheidungsfreude, Durchsetzungsverm\u00f6gen und Teamf\u00e4higkeit<\/li><li>Sicherheit im Umgang mit MS Office<\/li><li>Lern- und Innovationsbereitschaft<\/li><\/ul><p>Sofern du die beamtenrechtlichen Voraussetzungen, wie beispielsweise die Altersgrenze oder die Staatsb\u00fcrgerschaft, nicht erf\u00fcllst, ist das duale Studium auch im Besch\u00e4ftigtenverh\u00e4ltnis m\u00f6glich.<\/p><p>Weitere Infos zum Studium findest du hier: <a href=\"https:\/\/www.nsi-hsvn.de\/hochschule\/bachelor-of-arts\/verwaltungswissenschaft.html\" target=\"_blank\" rel=\"noopener\">NSI<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4321\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4321\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h2 class=\"e-n-accordion-item-title-text\"> Mehr Infos zum Dualen Studium der Sozialen Arbeit <\/h2><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4321\" class=\"elementor-element elementor-element-a3e74b5 e-flex e-con-boxed e-con e-child\" data-id=\"a3e74b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4321\" class=\"elementor-element elementor-element-7876b76 e-con-full e-flex e-con e-child\" data-id=\"7876b76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f65ad33 elementor-widget elementor-widget-text-editor\" data-id=\"f65ad33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das duale Studium Soziale Arbeit dauert dreieinhalb Jahre, die sich in theoretische und praktische Abschnitte aufteilen, und endet mit dem Abschluss Bachelor of Arts (B.&nbsp;A.).<\/p>\n<p>Du studierst an der HSW \u2013 der Hochschule Weserbergland in Hameln \u2013 p\u00e4dagogische, psychologische, rechtliche und medizinische Themen.&nbsp;In den praktischen Zeiten bist du \u00fcberwiegend im Amt f\u00fcr Jugend und Inklusion unseres Landkreises im Einsatz.<\/p>\n<p>Selbstverst\u00e4ndlich \u00fcbernehmen wir die Studiengeb\u00fchren und du erh\u00e4ltst eine Verg\u00fctung in H\u00f6he von 1.550,00 Euro.<\/p>\n<p>F\u00fcr ein erfolgreiches Studium musst du Folgendes mitbringen:<\/p>\n<ul>\n<li>mindestens Fachhochschulreife<\/li>\n<li>soziales Engagement und Interesse an Menschen<\/li>\n<li>kommunikative St\u00e4rke und Empathie<\/li>\n<li>Sensibilit\u00e4t und Taktgef\u00fchl im Umgang mit Menschen<\/li>\n<li>Entscheidungsfreude, Durchsetzungsverm\u00f6gen und Teamf\u00e4higkeit<\/li>\n<li>Sicherheit im Umgang mit MS Office<\/li>\n<li>Lern- und Innovationsbereitschaft<\/li>\n<\/ul>\n<p>Mehr Infos zum Studium findest du hier: <a href=\"https:\/\/www.hsw-hameln.de\/studiengaenge\/soziale-arbeit-duales-bachelorstudium\/\" target=\"_blank\" rel=\"noopener\">HSW<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4322\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4322\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h2 class=\"e-n-accordion-item-title-text\"> So wirst du von Anfang an unterst\u00fctzt <\/h2><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4322\" class=\"elementor-element elementor-element-39d3425 e-con-full e-flex e-con e-child\" data-id=\"39d3425\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-221bcae elementor-widget elementor-widget-text-editor\" data-id=\"221bcae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Start in ein neues Studium bringt viele spannende Herausforderungen mit sich und genau dabei lassen wir dich nicht allein. Uns ist wichtig, dass du dich von Anfang an gut aufgehoben f\u00fchlst, schnell Anschluss findest und dich fachlich sowie pers\u00f6nlich weiterentwickeln kannst. Deshalb bieten wir dir ein umfassendes Unterst\u00fctzungsangebot, das weit \u00fcber den ersten Tag hinausgeht.<\/p><p>Das kannst du von uns erwarten:<\/p><ul class=\" ikiss-unordered-list\"><li>eine Einf\u00fchrungswoche mit vielen interessanten Kontakten und Teamtrainings<\/li><li>ein Onboarding mit einer pers\u00f6nlichen Lots:in<\/li><li>eine feste Ansprechperson w\u00e4hrend des gesamten Studiums (Ausbildungsleitung)<\/li><li>Teamwork und einen modernen Arbeitsplatz<\/li><li>ein offenes, wertsch\u00e4tzendes Arbeitsklima<\/li><li>Mitarbeitergespr\u00e4che zur Orientierung<\/li><li>zahlreiche Fort- und Weiterbildungsangebote<\/li><li>betriebliche Gesundheitsf\u00f6rderung mit Sportangeboten<\/li><li>Fahrtkostenerstattung<\/li><li>eigenst\u00e4ndiges Arbeiten im Rahmen unserer Azubifirma\u00a0<span lang=\"en\">Juniors<\/span><\/li><li>die Bearbeitung eigener Projekte<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4323\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4323\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h2 class=\"e-n-accordion-item-title-text\"> Welche Perspektiven dir nach dem Abschluss offenstehen <\/h2><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4323\" class=\"elementor-element elementor-element-c90acd4 e-con-full e-flex e-con e-child\" data-id=\"c90acd4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd12d2 elementor-widget elementor-widget-text-editor\" data-id=\"fdd12d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nach dem Studium erwarten dich hervorragende \u00dcbernahmechancen in vielf\u00e4ltigen Aufgabenbereichen. Ein pers\u00f6nliches Mentoring-Programm begleitet dich beim Einstieg in deine neue Rolle und sorgt f\u00fcr einen gelungenen Start. Auch ein anschlie\u00dfendes Masterstudium ist grunds\u00e4tzlich m\u00f6glich und kann im Einzelfall durch den Landkreis unterst\u00fctzt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4324\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4324\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h2 class=\"e-n-accordion-item-title-text\"> Wann und wie l\u00e4uft das Bewerbungsverfahren ab <\/h2><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4324\" class=\"elementor-element elementor-element-4347d60 e-con-full e-flex e-con e-child\" data-id=\"4347d60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-308027d elementor-widget elementor-widget-text-editor\" data-id=\"308027d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr beide dualen Studieng\u00e4nge \u2013 Verwaltung und Soziale Arbeit \u2013 ist eine fr\u00fchzeitige Bewerbung erforderlich, da die Verfahren bereits im Jahr vor Studienbeginn stattfinden.<\/p>\n<p>Verwaltung:<br>Das Studium beginnt jeweils am 1. August. Die Bewerbungsphase startet im Jahr davor ab dem 1. Juni. Im Rahmen des Auswahlverfahrens ist ein Eignungstest zu absolvieren, der die fachliche und pers\u00f6nliche Eignung pr\u00fcft.<\/p>\n<p>Soziale Arbeit:<br>Hier beginnt das Studium am 1. Oktober. Die Bewerbung muss ebenfalls fr\u00fchzeitig eingereicht werden und zwar ab dem 1. November des Vorjahres. Auch in diesem Verfahren findet ein Eignungstest statt, der Bestandteil der Auswahl ist.<\/p>\n<p>Nach Bestehen des Eignungstests folgt in der Regel ein pers\u00f6nliches Vorstellungsgespr\u00e4ch, in dem sowohl die Motivation als auch die individuellen St\u00e4rken n\u00e4her beleuchtet werden. Bewerber:innen sollten sich daher nicht nur fachlich, sondern auch pers\u00f6nlich gut auf das Auswahlverfahren vorbereiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e753a3a e-flex e-con-boxed e-con e-parent\" data-id=\"e753a3a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e57c9e e-con-full e-flex e-con e-child\" data-id=\"7e57c9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b25015d elementor-arrows-position-outside elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"b25015d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Duales Studium&quot;,&quot;_id&quot;:&quot;9790b47&quot;},{&quot;slide_title&quot;:&quot;Ausbildung&quot;,&quot;_id&quot;:&quot;8f809df&quot;},{&quot;slide_title&quot;:&quot;Ausbildungsleitung&quot;,&quot;_id&quot;:&quot;c0a2422&quot;},{&quot;slide_title&quot;:&quot;Recruiting&quot;,&quot;_id&quot;:&quot;33ef987&quot;},{&quot;slide_title&quot;:&quot;Sozialpsychiatrischer Dienst&quot;,&quot;_id&quot;:&quot;4083cd2&quot;},{&quot;slide_title&quot;:&quot;Gesundheitsamt&quot;,&quot;_id&quot;:&quot;d087e61&quot;},{&quot;slide_title&quot;:&quot;Soziales&quot;,&quot;_id&quot;:&quot;869b4a0&quot;},{&quot;slide_title&quot;:&quot;Sozialamt&quot;,&quot;_id&quot;:&quot;90c0353&quot;},{&quot;slide_title&quot;:&quot;IT und Digitalisierung&quot;,&quot;_id&quot;:&quot;496f187&quot;},{&quot;slide_title&quot;:&quot;Leitstelle&quot;,&quot;_id&quot;:&quot;8e1ccf2&quot;},{&quot;slide_title&quot;:&quot;Umwelt&quot;,&quot;_id&quot;:&quot;01ac354&quot;},{&quot;slide_title&quot;:&quot;Work-Life&quot;,&quot;_id&quot;:&quot;c1d95fe&quot;},{&quot;slide_title&quot;:&quot;F\\u00fchrungskr\\u00e4fte&quot;,&quot;_id&quot;:&quot;e1a159b&quot;},{&quot;slide_title&quot;:&quot;F\\u00fchrungskr\\u00e4fte Teilzeit&quot;,&quot;_id&quot;:&quot;4834ddc&quot;},{&quot;slide_title&quot;:&quot;Quereinsttieg&quot;,&quot;_id&quot;:&quot;fa0326c&quot;},{&quot;slide_title&quot;:&quot;Quereinsttieg FAQ&quot;,&quot;_id&quot;:&quot;f857b7c&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;offset_sides&quot;:&quot;both&quot;,&quot;offset_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;offset_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;offset_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_width_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51e9c84 e-flex e-con-boxed e-con e-child\" data-id=\"51e9c84\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0eb42a8 elementor-widget elementor-widget-video\" data-id=\"0eb42a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNTU2Mjk5NTg\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPWMxYmYyNDQyZTQjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b94fe3f e-con-full e-flex e-con e-child\" data-id=\"b94fe3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7d43a7 elementor-widget elementor-widget-heading\" data-id=\"e7d43a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Duales Studium<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6323e elementor-widget elementor-widget-text-editor\" data-id=\"5e6323e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Verena und Jannes erz\u00e4hlen von ihrem dualen Studium in der Verwaltung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72455b5 e-flex e-con-boxed e-con e-child\" data-id=\"72455b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8fcff8 elementor-widget elementor-widget-video\" data-id=\"b8fcff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNjQ0MzU5OTI\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTA4NmJiYzcxZmEjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d6dcf9 e-con-full e-flex e-con e-child\" data-id=\"0d6dcf9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecc08ae elementor-widget elementor-widget-heading\" data-id=\"ecc08ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ausbildung<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4449e0 elementor-widget elementor-widget-text-editor\" data-id=\"e4449e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kartal und Julia berichten von ihrer Ausbildung zur\/zum Verwaltungsfachangestellten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-489620d e-flex e-con-boxed e-con e-child\" data-id=\"489620d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6134cbe elementor-widget elementor-widget-video\" data-id=\"6134cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExNDg5MDM1MTQ\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTgwYTA3OWU3ZmQjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8a5975 e-con-full e-flex e-con e-child\" data-id=\"a8a5975\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14a76ae elementor-widget elementor-widget-heading\" data-id=\"14a76ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ausbildungsleitungen<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8249082 elementor-widget elementor-widget-text-editor\" data-id=\"8249082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Leonie Str\u00fcber und Celine Chill erkl\u00e4ren wie der Einstieg \u00fcber eine Ausbildung oder ein Duales Studium gelingt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36b4820 e-flex e-con-boxed e-con e-child\" data-id=\"36b4820\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-500d301 elementor-widget elementor-widget-video\" data-id=\"500d301\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExNDg5MDM0MzE\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPWZjNTRlYzg2ZGYjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65d69fa e-con-full e-flex e-con e-child\" data-id=\"65d69fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6505892 elementor-widget elementor-widget-heading\" data-id=\"6505892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Recruiting<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a5f736 elementor-widget elementor-widget-text-editor\" data-id=\"2a5f736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esther von Borcke und Laura V\u00f6lker stellen unser Recruiting vor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e50b8d e-flex e-con-boxed e-con e-child\" data-id=\"5e50b8d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c12d9 elementor-widget elementor-widget-video\" data-id=\"e8c12d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExNDcyNzMyNDk\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTkzY2NkN2RjMWYjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62a81bb e-con-full e-flex e-con e-child\" data-id=\"62a81bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2ccbc3 elementor-widget elementor-widget-heading\" data-id=\"a2ccbc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Rufbereitschaft PsychKG<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e910fe elementor-widget elementor-widget-text-editor\" data-id=\"4e910fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sebastian Brandenburg \u00fcbernimmt neben seiner T\u00e4tigkeit als Umwelttechniker die Rufbereitschaft f\u00fcr PsychKG.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e32af44 e-flex e-con-boxed e-con e-child\" data-id=\"e32af44\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e808656 elementor-widget elementor-widget-video\" data-id=\"e808656\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNjAyMzY0OTA\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTk4MzY4ZjZjNzAjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-377cfd3 e-con-full e-flex e-con e-child\" data-id=\"377cfd3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9e4136 elementor-widget elementor-widget-heading\" data-id=\"f9e4136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gesundheitsamt<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e413f7c elementor-widget elementor-widget-text-editor\" data-id=\"e413f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dr. Ingrid Behnke erz\u00e4hlt, warum sie sich als \u00c4rztin f\u00fcr uns als Arbeitgeber entschieden hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"7\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88f7ccc e-flex e-con-boxed e-con e-child\" data-id=\"88f7ccc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c599f24 elementor-widget elementor-widget-video\" data-id=\"c599f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNzUyNTcxODk\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPWRkODQ4MjRlYjUjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c4c88c e-con-full e-flex e-con e-child\" data-id=\"5c4c88c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-846ef9d elementor-widget elementor-widget-heading\" data-id=\"846ef9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Amt f\u00fcr Jugend &amp; Inklusion<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a8d56 elementor-widget elementor-widget-text-editor\" data-id=\"72a8d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Michelle Gold und Lena Klapproth berichten von ihrer Arbeit mit beeintr\u00e4chtigten Kindern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"8\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77f276e e-flex e-con-boxed e-con e-child\" data-id=\"77f276e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f62e92 elementor-widget elementor-widget-video\" data-id=\"5f62e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExMTQ3ODY0MzQ\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTRiYTk1NmIyY2YjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d364b22 e-con-full e-flex e-con e-child\" data-id=\"d364b22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c73f7d elementor-widget elementor-widget-heading\" data-id=\"5c73f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sozialamt<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fcb4bd elementor-widget elementor-widget-text-editor\" data-id=\"5fcb4bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Christopher Maa\u00df und Thomas R\u00f6mhild berichten \u00fcber ihren Arbeitsalltag im Sozialamt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"9\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f316b82 e-flex e-con-boxed e-con e-child\" data-id=\"f316b82\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07d1714 elementor-widget elementor-widget-video\" data-id=\"07d1714\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExMTU0Nzk3OTM\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTcwNDVlOWFkMmIjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f3f93a e-con-full e-flex e-con e-child\" data-id=\"2f3f93a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6f3786 elementor-widget elementor-widget-heading\" data-id=\"d6f3786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">IT<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3cac66 elementor-widget elementor-widget-text-editor\" data-id=\"f3cac66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sven Behrens und Samim Shojai erz\u00e4hlen von den vielf\u00e4ltigen Aufgaben im Bereich unserer IT.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"10\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d230b5 e-flex e-con-boxed e-con e-child\" data-id=\"6d230b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c0c160 elementor-widget elementor-widget-video\" data-id=\"6c0c160\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExMTQxNTU3NTY\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTdjMTkyZmEyN2MjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f051c7d e-con-full e-flex e-con e-child\" data-id=\"f051c7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5afd3e9 elementor-widget elementor-widget-heading\" data-id=\"5afd3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Kooperative Regionalleitstelle<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e545a0f elementor-widget elementor-widget-text-editor\" data-id=\"e545a0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patrick Schwedt und Fenja Meier-S\u00f6ffker geben einen Einblick hinter die Kulissen unserer Leitstelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"11\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9467b01 e-flex e-con-boxed e-con e-child\" data-id=\"9467b01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8dada elementor-widget elementor-widget-video\" data-id=\"fd8dada\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzExMzIwMzc2MjY\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTVjZTA1YjM0OGIjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3eefe85 e-con-full e-flex e-con e-child\" data-id=\"3eefe85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4952b7f elementor-widget elementor-widget-heading\" data-id=\"4952b7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Natur- und Umweltschutz<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9eb6f5 elementor-widget elementor-widget-text-editor\" data-id=\"d9eb6f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Frau Siekmann und Herr Nolte geben Einblicke in ihre Arbeit als Umweltingenieur:innen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"12\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2954daa e-flex e-con-boxed e-con e-child\" data-id=\"2954daa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca43baa elementor-widget elementor-widget-video\" data-id=\"ca43baa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNjAyMzYzNDY\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTM5MTlhYmFmOGIjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf13ab9 e-con-full e-flex e-con e-child\" data-id=\"cf13ab9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-415dfa8 elementor-widget elementor-widget-heading\" data-id=\"415dfa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Work-Life-Balance<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8341f02 elementor-widget elementor-widget-text-editor\" data-id=\"8341f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Manon M\u00fcller erz\u00e4hlt von ihrem Beruf und der Arbeitszeitgestaltung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"13\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc93fd e-flex e-con-boxed e-con e-child\" data-id=\"6dc93fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-823f235 elementor-widget elementor-widget-video\" data-id=\"823f235\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNTc0MzQxNDU\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTUwMTYyNWFjOTkjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8f61cd e-con-full e-flex e-con e-child\" data-id=\"a8f61cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7cf39a elementor-widget elementor-widget-heading\" data-id=\"f7cf39a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">F\u00fchrungskr\u00e4fte<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e90600 elementor-widget elementor-widget-text-editor\" data-id=\"4e90600\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Helena Winter und Felix Eisenhuth sind zwei junge F\u00fchrungskr\u00e4fte, die Einblick in ihre F\u00fchrungskr\u00e4fteentwicklung geben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"14\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59d2edb e-flex e-con-boxed e-con e-child\" data-id=\"59d2edb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec7f42 elementor-widget elementor-widget-video\" data-id=\"1ec7f42\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwNjAyMzY2NDQ\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTQ5Mjc0ZTQ3OTEjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ceb0e9 e-con-full e-flex e-con e-child\" data-id=\"0ceb0e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab2292 elementor-widget elementor-widget-heading\" data-id=\"3ab2292\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">F\u00fchrungskr\u00e4fte in Teilzeit<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fab4fb6 elementor-widget elementor-widget-text-editor\" data-id=\"fab4fb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Annika Asche und Claus Hake f\u00fchren in Teilzeit. Hier teilen sie ihre Erfahrungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"15\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac66681 e-flex e-con-boxed e-con e-child\" data-id=\"ac66681\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa05ef elementor-widget elementor-widget-video\" data-id=\"2fa05ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwOTYzNDkzMDc\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTBhYzBmMTE4MTIjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7c24f8 e-con-full e-flex e-con e-child\" data-id=\"c7c24f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-202a8d0 elementor-widget elementor-widget-heading\" data-id=\"202a8d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Quereinstieg<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8248b1 elementor-widget elementor-widget-text-editor\" data-id=\"e8248b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Daniela Blom ist als Quereinsteigerin zu uns gekommen und hat sich durch Weiterbildungen weiterqualifiziert.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"16\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 von 16\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2f68fd e-flex e-con-boxed e-con e-child\" data-id=\"b2f68fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae1e53 elementor-widget elementor-widget-video\" data-id=\"6ae1e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"vimeo-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0iZWxlbWVudG9yLXZpZGVvLWlmcmFtZSIgYWxsb3dmdWxsc2NyZWVuIGFsbG93PSJjbGlwYm9hcmQtd3JpdGUiIHRpdGxlPSJ2aW1lbyBWaWRlbyBQbGF5ZXIiIHNyYz0iaHR0cHM6Ly9wbGF5ZXIudmltZW8uY29tL3ZpZGVvLzEwOTc0NzY2MTA\/Y29sb3ImYW1wO2F1dG9wYXVzZT0wJmFtcDtsb29wPTAmYW1wO211dGVkPTAmYW1wO3RpdGxlPTAmYW1wO3BvcnRyYWl0PTAmYW1wO2J5bGluZT0wJmFtcDtoPTA2OWMxOWI5ZGYjdD0iPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-vimeo\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-vimeo-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Vimeo<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c19d03e e-con-full e-flex e-con e-child\" data-id=\"c19d03e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db77e4f elementor-widget elementor-widget-heading\" data-id=\"db77e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">FAQ zum Quereinstieg<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-028b41b elementor-widget elementor-widget-text-editor\" data-id=\"028b41b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Leonie Str\u00fcber beantwortet Fragen zum Quereinstieg und den Angestelltenlehrg\u00e4ngen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-acd9171 e-flex e-con-boxed e-con e-parent\" data-id=\"acd9171\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-39ae606 e-con-full e-flex e-con e-child\" data-id=\"39ae606\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f50b21 elementor-widget elementor-widget-heading\" data-id=\"9f50b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jetzt Teil unseres Teams werden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfe522f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dfe522f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/karriere.hameln-pyrmont.de\/index.php\/stellenangebote\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Stellenangebote ansehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Studium Dein Karrierestart mit Perspektive. Hier bin ich HaPy, weil der Landkreis die Weiterbildung seiner Mitarbeitenden stetig f\u00f6rdert. Ich habe dadurch direkt im Anschluss meiner Ausbildung die M\u00f6glichkeit auf einen Studienplatz erhalten. Verena BorchersDuale Studentin der Verwaltungswissenschaften Auszubildende &amp; Studierende 0 Dein Einstieg beim Landkreis Hameln-Pyrmont Mit einem Studium in der \u00f6ffentlichen Verwaltung liegst du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":378,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1309","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studium - Karriere Landkreis Hameln-Pyrmont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studium - Karriere Landkreis Hameln-Pyrmont\" \/>\n<meta property=\"og:description\" content=\"Studium Dein Karrierestart mit Perspektive. Hier bin ich HaPy, weil der Landkreis die Weiterbildung seiner Mitarbeitenden stetig f\u00f6rdert. Ich habe dadurch direkt im Anschluss meiner Ausbildung die M\u00f6glichkeit auf einen Studienplatz erhalten. Verena BorchersDuale Studentin der Verwaltungswissenschaften Auszubildende &amp; Studierende 0 Dein Einstieg beim Landkreis Hameln-Pyrmont Mit einem Studium in der \u00f6ffentlichen Verwaltung liegst du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/\" \/>\n<meta property=\"og:site_name\" content=\"Karriere Landkreis Hameln-Pyrmont\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T09:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/\",\"url\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/\",\"name\":\"Studium - Karriere Landkreis Hameln-Pyrmont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/0V0A5234-scaled.jpg\",\"datePublished\":\"2025-06-16T13:06:23+00:00\",\"dateModified\":\"2026-05-07T09:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/0V0A5234-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/0V0A5234-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/studium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einstiege\",\"item\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/index.php\\\/einstiege\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#website\",\"url\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/\",\"name\":\"Karriere Landkreis Hameln-Pyrmont\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#organization\",\"name\":\"Karriere Landkreis Hameln-Pyrmont\",\"url\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo_landkreis-hameln-pyrmont.png\",\"contentUrl\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo_landkreis-hameln-pyrmont.png\",\"width\":600,\"height\":345,\"caption\":\"Karriere Landkreis Hameln-Pyrmont\"},\"image\":{\"@id\":\"https:\\\/\\\/karriere.hameln-pyrmont.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studium - Karriere Landkreis Hameln-Pyrmont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/","og_locale":"de_DE","og_type":"article","og_title":"Studium - Karriere Landkreis Hameln-Pyrmont","og_description":"Studium Dein Karrierestart mit Perspektive. Hier bin ich HaPy, weil der Landkreis die Weiterbildung seiner Mitarbeitenden stetig f\u00f6rdert. Ich habe dadurch direkt im Anschluss meiner Ausbildung die M\u00f6glichkeit auf einen Studienplatz erhalten. Verena BorchersDuale Studentin der Verwaltungswissenschaften Auszubildende &amp; Studierende 0 Dein Einstieg beim Landkreis Hameln-Pyrmont Mit einem Studium in der \u00f6ffentlichen Verwaltung liegst du [&hellip;]","og_url":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/","og_site_name":"Karriere Landkreis Hameln-Pyrmont","article_modified_time":"2026-05-07T09:36:36+00:00","og_image":[{"url":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/","url":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/","name":"Studium - Karriere Landkreis Hameln-Pyrmont","isPartOf":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/#primaryimage"},"image":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/#primaryimage"},"thumbnailUrl":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg","datePublished":"2025-06-16T13:06:23+00:00","dateModified":"2026-05-07T09:36:36+00:00","breadcrumb":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/#primaryimage","url":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg","contentUrl":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/07\/0V0A5234-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/studium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/karriere.hameln-pyrmont.de\/"},{"@type":"ListItem","position":2,"name":"Einstiege","item":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/einstiege\/"},{"@type":"ListItem","position":3,"name":"Studium"}]},{"@type":"WebSite","@id":"https:\/\/karriere.hameln-pyrmont.de\/#website","url":"https:\/\/karriere.hameln-pyrmont.de\/","name":"Karriere Landkreis Hameln-Pyrmont","description":"","publisher":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karriere.hameln-pyrmont.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/karriere.hameln-pyrmont.de\/#organization","name":"Karriere Landkreis Hameln-Pyrmont","url":"https:\/\/karriere.hameln-pyrmont.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/karriere.hameln-pyrmont.de\/#\/schema\/logo\/image\/","url":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/03\/logo_landkreis-hameln-pyrmont.png","contentUrl":"https:\/\/karriere.hameln-pyrmont.de\/wp-content\/uploads\/2025\/03\/logo_landkreis-hameln-pyrmont.png","width":600,"height":345,"caption":"Karriere Landkreis Hameln-Pyrmont"},"image":{"@id":"https:\/\/karriere.hameln-pyrmont.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/pages\/1309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/comments?post=1309"}],"version-history":[{"count":142,"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/pages\/1309\/revisions"}],"predecessor-version":[{"id":6627,"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/pages\/1309\/revisions\/6627"}],"up":[{"embeddable":true,"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/pages\/378"}],"wp:attachment":[{"href":"https:\/\/karriere.hameln-pyrmont.de\/index.php\/wp-json\/wp\/v2\/media?parent=1309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}